{"id":137,"count":983,"description":"As a dedicated online doll store, LOVEPUPPEN offers a selection of realistic love dolls in various weight classes, the dolls presented here weigh between 31 kg and 40 kg.","link":"https:\/\/www.lovepuppen.com\/en\/product-category\/31-40kg\/","name":"31 - 40KG","slug":"31-40kg","taxonomy":"product_cat","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>31 - 40KG Sexpuppen Lebensgro\u00dfe 31 - 40KG realistische Liebespuppe Mittelschwere Real-Life-Puppe - LOVEPUPPEN<\/title>\n<meta name=\"description\" content=\"Als mittelschwer gelten lebensgro\u00dfe Sexpuppen zwischen 30 kg und 40 kg. Sie neigen dazu, echten Menschen n\u00e4her zu sein.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lovepuppen.com\/en\/product-category\/31-40kg\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"31 - 40KG Sexpuppen Lebensgro\u00dfe 31 - 40KG realistische Liebespuppe Mittelschwere Real-Life-Puppe - LOVEPUPPEN\" \/>\n<meta property=\"og:description\" content=\"Als mittelschwer gelten lebensgro\u00dfe Sexpuppen zwischen 30 kg und 40 kg. Sie neigen dazu, echten Menschen n\u00e4her zu sein.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lovepuppen.com\/en\/product-category\/31-40kg\/\" \/>\n<meta property=\"og:site_name\" content=\"LOVEPUPPEN\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.lovepuppen.com\/product-category\/31-40kg\/\",\"url\":\"https:\/\/www.lovepuppen.com\/product-category\/31-40kg\/\",\"name\":\"31 - 40KG Sexpuppen Lebensgro\u00dfe 31 - 40KG realistische Liebespuppe Mittelschwere Real-Life-Puppe - LOVEPUPPEN\",\"isPartOf\":{\"@id\":\"https:\/\/www.lovepuppen.com\/#website\"},\"description\":\"Als mittelschwer gelten lebensgro\u00dfe Sexpuppen zwischen 30 kg und 40 kg. Sie neigen dazu, echten Menschen n\u00e4her zu sein.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.lovepuppen.com\/product-category\/31-40kg\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.lovepuppen.com\/product-category\/31-40kg\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.lovepuppen.com\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"31 - 40KG\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.lovepuppen.com\/#website\",\"url\":\"https:\/\/www.lovepuppen.com\/\",\"name\":\"LOVEPUPPEN\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.lovepuppen.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.lovepuppen.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.lovepuppen.com\/#organization\",\"name\":\"LOVEPUPPEN\",\"url\":\"https:\/\/www.lovepuppen.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.lovepuppen.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.lovepuppen.com\/wp-content\/uploads\/2024\/02\/cropped-lovepuppen-logo-06.png\",\"contentUrl\":\"https:\/\/www.lovepuppen.com\/wp-content\/uploads\/2024\/02\/cropped-lovepuppen-logo-06.png\",\"width\":240,\"height\":80,\"caption\":\"LOVEPUPPEN\"},\"image\":{\"@id\":\"https:\/\/www.lovepuppen.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"31 - 40KG sex dolls Life-size 31 - 40KG realistic love doll Medium-weight real-life doll - LOVEPUPPEN","description":"Life-size sex dolls weighing between 30 kg and 40 kg are considered to be of medium weight. They tend to be closer to real people.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lovepuppen.com\/en\/product-category\/31-40kg\/","og_locale":"en_US","og_type":"article","og_title":"31 - 40KG Sexpuppen Lebensgro\u00dfe 31 - 40KG realistische Liebespuppe Mittelschwere Real-Life-Puppe - LOVEPUPPEN","og_description":"Als mittelschwer gelten lebensgro\u00dfe Sexpuppen zwischen 30 kg und 40 kg. Sie neigen dazu, echten Menschen n\u00e4her zu sein.","og_url":"https:\/\/www.lovepuppen.com\/en\/product-category\/31-40kg\/","og_site_name":"LOVEPUPPEN","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.lovepuppen.com\/product-category\/31-40kg\/","url":"https:\/\/www.lovepuppen.com\/product-category\/31-40kg\/","name":"31 - 40KG sex dolls Life-size 31 - 40KG realistic love doll Medium-weight real-life doll - LOVEPUPPEN","isPartOf":{"@id":"https:\/\/www.lovepuppen.com\/#website"},"description":"Life-size sex dolls weighing between 30 kg and 40 kg are considered to be of medium weight. They tend to be closer to real people.","breadcrumb":{"@id":"https:\/\/www.lovepuppen.com\/product-category\/31-40kg\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.lovepuppen.com\/product-category\/31-40kg\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.lovepuppen.com\/it\/"},{"@type":"ListItem","position":2,"name":"31 - 40KG"}]},{"@type":"WebSite","@id":"https:\/\/www.lovepuppen.com\/#website","url":"https:\/\/www.lovepuppen.com\/","name":"LOVEPUPPEN","description":"","publisher":{"@id":"https:\/\/www.lovepuppen.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lovepuppen.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.lovepuppen.com\/#organization","name":"LOVEPUPPEN","url":"https:\/\/www.lovepuppen.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.lovepuppen.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.lovepuppen.com\/wp-content\/uploads\/2024\/02\/cropped-lovepuppen-logo-06.png","contentUrl":"https:\/\/www.lovepuppen.com\/wp-content\/uploads\/2024\/02\/cropped-lovepuppen-logo-06.png","width":240,"height":80,"caption":"LOVEPUPPEN"},"image":{"@id":"https:\/\/www.lovepuppen.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.lovepuppen.com\/en\/wp-json\/wp\/v2\/product_cat\/137","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lovepuppen.com\/en\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/www.lovepuppen.com\/en\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/www.lovepuppen.com\/en\/wp-json\/wp\/v2\/product?product_cat=137"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}